{"id":26491,"date":"2025-02-02T20:51:46","date_gmt":"2025-02-02T19:51:46","guid":{"rendered":"https:\/\/blogg.atl.nu\/abbotnas-sateri\/?p=26491"},"modified":"2025-02-02T20:51:46","modified_gmt":"2025-02-02T19:51:46","slug":"annu-mer-godseltema","status":"publish","type":"post","link":"https:\/\/blogg.atl.nu\/abbotnas-sateri\/2025\/02\/02\/annu-mer-godseltema\/","title":{"rendered":"\u00c4nnu mer g\u00f6dseltema"},"content":{"rendered":"<p><strong>Ny m\u00e5nad och s\u00e5 h\u00e4r l\u00e5ngt f\u00e5r februari godk\u00e4nt, i alla fall v\u00e4derm\u00e4ssigt n\u00e4r den erbjudit oss bra v\u00e4der f\u00f6r att forts\u00e4tta f\u00e5 ut dyngan dit den ska spridas senare i \u00e5r. Nu har vi lyckats t\u00f6mma plattan igen och \u00e4ven g\u00f6dslat ut den andra sidan hos dikorna.\u00a0<\/strong><\/p>\n<h3>Bra fas<\/h3>\n<p><strong>Tack vare denna helg och m\u00f6jligheterna v\u00e4dret gav oss s\u00e5 ligger vi nu i bra fas n\u00e4r det g\u00e4ller utl\u00e4ggning av komposter i f\u00e4lt.\u00a0<\/strong>Vi brukar ju som jag beskrivit tidigare f\u00f6rs\u00f6ka f\u00e5 ut s\u00e5 mycket av v\u00e5ran djurg\u00f6dsel i f\u00e4lten f\u00f6r att ligga i kompost d\u00e4r tills det ska spridas i h\u00f6st. Det finns m\u00e5nga bra f\u00f6rdelar med det. Dels sparar det en lastning om det kan ske direkt och sedan s\u00e5 har vi chansen att minska arbetsb\u00f6rdan eftersom att en del redan d\u00e5 \u00e4r utk\u00f6rt. Erfarenhetsm\u00e4ssigt vet jag att det absolut inte blir mindre att g\u00f6ra vartefter \u00e5ret g\u00e5r och s\u00e4songer drar ig\u00e5ng. Det \u00e4r inte alltid detta g\u00e5r och inte heller s\u00e5 smidigt som det gjorde nu, men nu gjorde det det och d\u00e5 f\u00e5r vi vara n\u00f6jda med det. S\u00e5 tack till v\u00e4dret f\u00f6r att det s\u00e5g till att detta var m\u00f6jligt!<\/p>\n<p>Det vi nu gjorde i helgen var att t\u00f6mma g\u00f6dselplattan (igen) och att g\u00f6dsla ut den andra sidan ur dikolag\u00e5rden. Den f\u00f6rsta sidan i dikolag\u00e5rden g\u00f6dslade vi ut f\u00f6rra m\u00e5ndagen. H\u00e4r kommer lite bilder fr\u00e5n helgens g\u00f6dseltema:<\/p>\n<figure id=\"attachment_26496\" aria-describedby=\"caption-attachment-26496\" style=\"width: 2560px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" class=\"size-full wp-image-26496\" src=\"https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/02\/DJI_0586-scaled.jpg\" alt=\"\" width=\"2560\" height=\"1918\" srcset=\"https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/02\/DJI_0586-scaled.jpg 2560w, https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/02\/DJI_0586-300x225.jpg 300w, https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/02\/DJI_0586-1024x767.jpg 1024w, https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/02\/DJI_0586-768x575.jpg 768w, https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/02\/DJI_0586-1536x1151.jpg 1536w, https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/02\/DJI_0586-2048x1534.jpg 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/><figcaption id=\"caption-attachment-26496\" class=\"wp-caption-text\">default<\/figcaption><\/figure>\n<figure id=\"attachment_26495\" aria-describedby=\"caption-attachment-26495\" style=\"width: 2560px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" class=\"size-full wp-image-26495\" src=\"https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/02\/DJI_0568-scaled.jpg\" alt=\"\" width=\"2560\" height=\"1918\" srcset=\"https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/02\/DJI_0568-scaled.jpg 2560w, https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/02\/DJI_0568-300x225.jpg 300w, https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/02\/DJI_0568-1024x767.jpg 1024w, https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/02\/DJI_0568-768x575.jpg 768w, https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/02\/DJI_0568-1536x1151.jpg 1536w, https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/02\/DJI_0568-2048x1534.jpg 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/><figcaption id=\"caption-attachment-26495\" class=\"wp-caption-text\">default<\/figcaption><\/figure>\n<figure id=\"attachment_26494\" aria-describedby=\"caption-attachment-26494\" style=\"width: 2560px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" class=\"size-full wp-image-26494\" src=\"https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/02\/DJI_0566-scaled.jpg\" alt=\"\" width=\"2560\" height=\"1918\" srcset=\"https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/02\/DJI_0566-scaled.jpg 2560w, https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/02\/DJI_0566-300x225.jpg 300w, https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/02\/DJI_0566-1024x767.jpg 1024w, https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/02\/DJI_0566-768x575.jpg 768w, https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/02\/DJI_0566-1536x1151.jpg 1536w, https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/02\/DJI_0566-2048x1534.jpg 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/><figcaption id=\"caption-attachment-26494\" class=\"wp-caption-text\">default<\/figcaption><\/figure>\n<figure id=\"attachment_26493\" aria-describedby=\"caption-attachment-26493\" style=\"width: 2560px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" class=\"size-full wp-image-26493\" src=\"https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/02\/DJI_0565-scaled.jpg\" alt=\"\" width=\"2560\" height=\"1696\" srcset=\"https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/02\/DJI_0565-scaled.jpg 2560w, https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/02\/DJI_0565-300x199.jpg 300w, https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/02\/DJI_0565-1024x679.jpg 1024w, https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/02\/DJI_0565-768x509.jpg 768w, https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/02\/DJI_0565-1536x1018.jpg 1536w, https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/02\/DJI_0565-2048x1357.jpg 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/><figcaption id=\"caption-attachment-26493\" class=\"wp-caption-text\">default<\/figcaption><\/figure>\n<p><img loading=\"lazy\" class=\"alignnone size-full wp-image-26490\" src=\"https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/02\/IMG_9722-scaled.jpeg\" alt=\"\" width=\"2560\" height=\"1920\" srcset=\"https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/02\/IMG_9722-scaled.jpeg 2560w, https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/02\/IMG_9722-300x225.jpeg 300w, https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/02\/IMG_9722-1024x768.jpeg 1024w, https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/02\/IMG_9722-768x576.jpeg 768w, https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/02\/IMG_9722-1536x1152.jpeg 1536w, https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/02\/IMG_9722-2048x1536.jpeg 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/> <img loading=\"lazy\" class=\"alignnone size-full wp-image-26489\" src=\"https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/02\/IMG_9724-scaled.jpeg\" alt=\"\" width=\"2560\" height=\"1920\" srcset=\"https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/02\/IMG_9724-scaled.jpeg 2560w, https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/02\/IMG_9724-300x225.jpeg 300w, https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/02\/IMG_9724-1024x768.jpeg 1024w, https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/02\/IMG_9724-768x576.jpeg 768w, https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/02\/IMG_9724-1536x1152.jpeg 1536w, https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/02\/IMG_9724-2048x1536.jpeg 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/> <img loading=\"lazy\" class=\"alignnone size-full wp-image-26488\" src=\"https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/02\/IMG_9726-scaled.jpeg\" alt=\"\" width=\"2560\" height=\"1920\" srcset=\"https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/02\/IMG_9726-scaled.jpeg 2560w, https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/02\/IMG_9726-300x225.jpeg 300w, https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/02\/IMG_9726-1024x768.jpeg 1024w, https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/02\/IMG_9726-768x576.jpeg 768w, https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/02\/IMG_9726-1536x1152.jpeg 1536w, https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/02\/IMG_9726-2048x1536.jpeg 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/> <img loading=\"lazy\" class=\"alignnone size-full wp-image-26487\" src=\"https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/02\/IMG_9727-scaled.jpeg\" alt=\"\" width=\"2560\" height=\"1920\" srcset=\"https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/02\/IMG_9727-scaled.jpeg 2560w, https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/02\/IMG_9727-300x225.jpeg 300w, https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/02\/IMG_9727-1024x768.jpeg 1024w, https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/02\/IMG_9727-768x576.jpeg 768w, https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/02\/IMG_9727-1536x1152.jpeg 1536w, https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/02\/IMG_9727-2048x1536.jpeg 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/> <img loading=\"lazy\" class=\"alignnone size-full wp-image-26486\" src=\"https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/02\/IMG_9730-scaled.jpeg\" alt=\"\" width=\"2560\" height=\"1920\" srcset=\"https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/02\/IMG_9730-scaled.jpeg 2560w, https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/02\/IMG_9730-300x225.jpeg 300w, https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/02\/IMG_9730-1024x768.jpeg 1024w, https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/02\/IMG_9730-768x576.jpeg 768w, https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/02\/IMG_9730-1536x1152.jpeg 1536w, https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/02\/IMG_9730-2048x1536.jpeg 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/> <img loading=\"lazy\" class=\"alignnone size-full wp-image-26485\" src=\"https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/02\/IMG_9732-scaled.jpeg\" alt=\"\" width=\"2560\" height=\"1920\" srcset=\"https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/02\/IMG_9732-scaled.jpeg 2560w, https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/02\/IMG_9732-300x225.jpeg 300w, https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/02\/IMG_9732-1024x768.jpeg 1024w, https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/02\/IMG_9732-768x576.jpeg 768w, https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/02\/IMG_9732-1536x1152.jpeg 1536w, https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/02\/IMG_9732-2048x1536.jpeg 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/> <img loading=\"lazy\" class=\"alignnone size-full wp-image-26484\" src=\"https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/02\/IMG_9733-scaled.jpeg\" alt=\"\" width=\"2560\" height=\"1920\" srcset=\"https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/02\/IMG_9733-scaled.jpeg 2560w, https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/02\/IMG_9733-300x225.jpeg 300w, https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/02\/IMG_9733-1024x768.jpeg 1024w, https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/02\/IMG_9733-768x576.jpeg 768w, https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/02\/IMG_9733-1536x1152.jpeg 1536w, https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/02\/IMG_9733-2048x1536.jpeg 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/> <img loading=\"lazy\" class=\"alignnone size-full wp-image-26483\" src=\"https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/02\/IMG_9735-scaled.jpeg\" alt=\"\" width=\"2560\" height=\"1920\" srcset=\"https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/02\/IMG_9735-scaled.jpeg 2560w, https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/02\/IMG_9735-300x225.jpeg 300w, https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/02\/IMG_9735-1024x768.jpeg 1024w, https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/02\/IMG_9735-768x576.jpeg 768w, https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/02\/IMG_9735-1536x1152.jpeg 1536w, https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/02\/IMG_9735-2048x1536.jpeg 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/> <img loading=\"lazy\" class=\"alignnone size-full wp-image-26482\" src=\"https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/02\/IMG_9739-scaled.jpeg\" alt=\"\" width=\"2560\" height=\"1920\" srcset=\"https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/02\/IMG_9739-scaled.jpeg 2560w, https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/02\/IMG_9739-300x225.jpeg 300w, https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/02\/IMG_9739-1024x768.jpeg 1024w, https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/02\/IMG_9739-768x576.jpeg 768w, https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/02\/IMG_9739-1536x1152.jpeg 1536w, https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/02\/IMG_9739-2048x1536.jpeg 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/> <img loading=\"lazy\" class=\"alignnone size-full wp-image-26480\" src=\"https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/02\/IMG_9750-scaled.jpeg\" alt=\"\" width=\"2560\" height=\"1920\" srcset=\"https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/02\/IMG_9750-scaled.jpeg 2560w, https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/02\/IMG_9750-300x225.jpeg 300w, https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/02\/IMG_9750-1024x768.jpeg 1024w, https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/02\/IMG_9750-768x576.jpeg 768w, https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/02\/IMG_9750-1536x1152.jpeg 1536w, https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/02\/IMG_9750-2048x1536.jpeg 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/> <img loading=\"lazy\" class=\"alignnone size-full wp-image-26479\" src=\"https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/02\/IMG_9752-scaled.jpeg\" alt=\"\" width=\"2560\" height=\"1920\" srcset=\"https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/02\/IMG_9752-scaled.jpeg 2560w, https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/02\/IMG_9752-300x225.jpeg 300w, https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/02\/IMG_9752-1024x768.jpeg 1024w, https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/02\/IMG_9752-768x576.jpeg 768w, https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/02\/IMG_9752-1536x1152.jpeg 1536w, https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/02\/IMG_9752-2048x1536.jpeg 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/> <img loading=\"lazy\" class=\"alignnone size-full wp-image-26478\" src=\"https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/02\/IMG_9753-scaled.jpeg\" alt=\"\" width=\"2560\" height=\"1920\" srcset=\"https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/02\/IMG_9753-scaled.jpeg 2560w, https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/02\/IMG_9753-300x225.jpeg 300w, https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/02\/IMG_9753-1024x768.jpeg 1024w, https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/02\/IMG_9753-768x576.jpeg 768w, https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/02\/IMG_9753-1536x1152.jpeg 1536w, https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/02\/IMG_9753-2048x1536.jpeg 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/> <img loading=\"lazy\" class=\"alignnone size-full wp-image-26477\" src=\"https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/02\/IMG_9756-scaled.jpeg\" alt=\"\" width=\"2560\" height=\"1920\" srcset=\"https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/02\/IMG_9756-scaled.jpeg 2560w, https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/02\/IMG_9756-300x225.jpeg 300w, https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/02\/IMG_9756-1024x768.jpeg 1024w, https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/02\/IMG_9756-768x576.jpeg 768w, https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/02\/IMG_9756-1536x1152.jpeg 1536w, https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/02\/IMG_9756-2048x1536.jpeg 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/> <img loading=\"lazy\" class=\"alignnone size-full wp-image-26476\" src=\"https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/02\/IMG_9757-scaled.jpeg\" alt=\"\" width=\"2560\" height=\"1920\" srcset=\"https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/02\/IMG_9757-scaled.jpeg 2560w, https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/02\/IMG_9757-300x225.jpeg 300w, https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/02\/IMG_9757-1024x768.jpeg 1024w, https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/02\/IMG_9757-768x576.jpeg 768w, https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/02\/IMG_9757-1536x1152.jpeg 1536w, https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/02\/IMG_9757-2048x1536.jpeg 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/> <img loading=\"lazy\" class=\"alignnone size-full wp-image-26475\" src=\"https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/02\/IMG_9765-scaled.jpeg\" alt=\"\" width=\"2560\" height=\"1920\" srcset=\"https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/02\/IMG_9765-scaled.jpeg 2560w, https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/02\/IMG_9765-300x225.jpeg 300w, https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/02\/IMG_9765-1024x768.jpeg 1024w, https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/02\/IMG_9765-768x576.jpeg 768w, https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/02\/IMG_9765-1536x1152.jpeg 1536w, https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/02\/IMG_9765-2048x1536.jpeg 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/> <img loading=\"lazy\" class=\"alignnone size-full wp-image-26474\" src=\"https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/02\/IMG_9768-scaled.jpeg\" alt=\"\" width=\"2560\" height=\"1920\" srcset=\"https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/02\/IMG_9768-scaled.jpeg 2560w, https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/02\/IMG_9768-300x225.jpeg 300w, https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/02\/IMG_9768-1024x768.jpeg 1024w, https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/02\/IMG_9768-768x576.jpeg 768w, https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/02\/IMG_9768-1536x1152.jpeg 1536w, https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/02\/IMG_9768-2048x1536.jpeg 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/> <img loading=\"lazy\" class=\"alignnone size-full wp-image-26473\" src=\"https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/02\/IMG_9770-scaled.jpeg\" alt=\"\" width=\"2560\" height=\"1920\" srcset=\"https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/02\/IMG_9770-scaled.jpeg 2560w, https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/02\/IMG_9770-300x225.jpeg 300w, https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/02\/IMG_9770-1024x768.jpeg 1024w, https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/02\/IMG_9770-768x576.jpeg 768w, https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/02\/IMG_9770-1536x1152.jpeg 1536w, https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/02\/IMG_9770-2048x1536.jpeg 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>Sk\u00f6nt nu att detta blev gjort! Extra sk\u00f6nt att vi nu har tv\u00e5 helt nya fr\u00e4scha b\u00e4ddar n\u00e4r kalvningarna drar ig\u00e5ng i slutet p\u00e5 m\u00e5naden. Mest f\u00f6r att det inneb\u00e4r att vi inte m\u00e5ste g\u00f6dsla ut n\u00e5got mer f\u00f6rens det \u00e4r tomt p\u00e5 djur inne och slipper g\u00f6ra det med massa kalvar i lag\u00e5rden.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ny m\u00e5nad och s\u00e5 h\u00e4r l\u00e5ngt f\u00e5r februari godk\u00e4nt, i alla fall v\u00e4derm\u00e4ssigt n\u00e4r den erbjudit oss bra v\u00e4der f\u00f6r att forts\u00e4tta f\u00e5 ut dyngan dit den ska spridas senare i \u00e5r. Nu har vi lyckats t\u00f6mma plattan igen och \u00e4ven g\u00f6dslat ut den andra sidan hos dikorna.\u00a0 Bra fas Tack vare denna helg och&#8230;<\/p>\n","protected":false},"author":361,"featured_media":26483,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u00c4nnu mer g\u00f6dseltema - Abbotn\u00e4s s\u00e4teri<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blogg.atl.nu\/abbotnas-sateri\/2025\/02\/02\/annu-mer-godseltema\/\" \/>\n<meta property=\"og:locale\" content=\"sv_SE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00c4nnu mer g\u00f6dseltema - Abbotn\u00e4s s\u00e4teri\" \/>\n<meta property=\"og:description\" content=\"Ny m\u00e5nad och s\u00e5 h\u00e4r l\u00e5ngt f\u00e5r februari godk\u00e4nt, i alla fall v\u00e4derm\u00e4ssigt n\u00e4r den erbjudit oss bra v\u00e4der f\u00f6r att forts\u00e4tta f\u00e5 ut dyngan dit den ska spridas senare i \u00e5r. Nu har vi lyckats t\u00f6mma plattan igen och \u00e4ven g\u00f6dslat ut den andra sidan hos dikorna.\u00a0 Bra fas Tack vare denna helg och...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blogg.atl.nu\/abbotnas-sateri\/2025\/02\/02\/annu-mer-godseltema\/\" \/>\n<meta property=\"og:site_name\" content=\"Abbotn\u00e4s s\u00e4teri\" \/>\n<meta property=\"article:author\" content=\"facebook.com\/mattiaswlarsson\" \/>\n<meta property=\"article:published_time\" content=\"2025-02-02T19:51:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/02\/IMG_9735-scaled.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1920\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Mattias Larsson\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Skriven av\" \/>\n\t<meta name=\"twitter:data1\" content=\"Mattias Larsson\" \/>\n\t<meta name=\"twitter:label2\" content=\"Ber\u00e4knad l\u00e4stid\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minuter\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/blogg.atl.nu\/abbotnas-sateri\/2025\/02\/02\/annu-mer-godseltema\/\",\"url\":\"https:\/\/blogg.atl.nu\/abbotnas-sateri\/2025\/02\/02\/annu-mer-godseltema\/\",\"name\":\"\u00c4nnu mer g\u00f6dseltema - Abbotn\u00e4s s\u00e4teri\",\"isPartOf\":{\"@id\":\"https:\/\/blogg.atl.nu\/abbotnas-sateri\/#website\"},\"datePublished\":\"2025-02-02T19:51:46+00:00\",\"dateModified\":\"2025-02-02T19:51:46+00:00\",\"author\":{\"@id\":\"https:\/\/blogg.atl.nu\/abbotnas-sateri\/#\/schema\/person\/3b681683e8c9711235140b74c4aad714\"},\"breadcrumb\":{\"@id\":\"https:\/\/blogg.atl.nu\/abbotnas-sateri\/2025\/02\/02\/annu-mer-godseltema\/#breadcrumb\"},\"inLanguage\":\"sv-SE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/blogg.atl.nu\/abbotnas-sateri\/2025\/02\/02\/annu-mer-godseltema\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/blogg.atl.nu\/abbotnas-sateri\/2025\/02\/02\/annu-mer-godseltema\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/blogg.atl.nu\/abbotnas-sateri\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00c4nnu mer g\u00f6dseltema\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/blogg.atl.nu\/abbotnas-sateri\/#website\",\"url\":\"https:\/\/blogg.atl.nu\/abbotnas-sateri\/\",\"name\":\"Abbotn\u00e4s s\u00e4teri\",\"description\":\"Mattias Larsson\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/blogg.atl.nu\/abbotnas-sateri\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"sv-SE\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/blogg.atl.nu\/abbotnas-sateri\/#\/schema\/person\/3b681683e8c9711235140b74c4aad714\",\"name\":\"Mattias Larsson\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"sv-SE\",\"@id\":\"https:\/\/blogg.atl.nu\/abbotnas-sateri\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/ab52d1a4abaa2f256164ccb2caf8dcfb?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/ab52d1a4abaa2f256164ccb2caf8dcfb?s=96&d=mm&r=g\",\"caption\":\"Mattias Larsson\"},\"sameAs\":[\"http:\/\/abbotnas.se\",\"facebook.com\/mattiaswlarsson\"],\"url\":\"https:\/\/blogg.atl.nu\/abbotnas-sateri\/author\/mlarsson\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00c4nnu mer g\u00f6dseltema - Abbotn\u00e4s s\u00e4teri","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blogg.atl.nu\/abbotnas-sateri\/2025\/02\/02\/annu-mer-godseltema\/","og_locale":"sv_SE","og_type":"article","og_title":"\u00c4nnu mer g\u00f6dseltema - Abbotn\u00e4s s\u00e4teri","og_description":"Ny m\u00e5nad och s\u00e5 h\u00e4r l\u00e5ngt f\u00e5r februari godk\u00e4nt, i alla fall v\u00e4derm\u00e4ssigt n\u00e4r den erbjudit oss bra v\u00e4der f\u00f6r att forts\u00e4tta f\u00e5 ut dyngan dit den ska spridas senare i \u00e5r. Nu har vi lyckats t\u00f6mma plattan igen och \u00e4ven g\u00f6dslat ut den andra sidan hos dikorna.\u00a0 Bra fas Tack vare denna helg och...","og_url":"https:\/\/blogg.atl.nu\/abbotnas-sateri\/2025\/02\/02\/annu-mer-godseltema\/","og_site_name":"Abbotn\u00e4s s\u00e4teri","article_author":"facebook.com\/mattiaswlarsson","article_published_time":"2025-02-02T19:51:46+00:00","og_image":[{"width":2560,"height":1920,"url":"https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/02\/IMG_9735-scaled.jpeg","type":"image\/jpeg"}],"author":"Mattias Larsson","twitter_card":"summary_large_image","twitter_misc":{"Skriven av":"Mattias Larsson","Ber\u00e4knad l\u00e4stid":"6 minuter"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/blogg.atl.nu\/abbotnas-sateri\/2025\/02\/02\/annu-mer-godseltema\/","url":"https:\/\/blogg.atl.nu\/abbotnas-sateri\/2025\/02\/02\/annu-mer-godseltema\/","name":"\u00c4nnu mer g\u00f6dseltema - Abbotn\u00e4s s\u00e4teri","isPartOf":{"@id":"https:\/\/blogg.atl.nu\/abbotnas-sateri\/#website"},"datePublished":"2025-02-02T19:51:46+00:00","dateModified":"2025-02-02T19:51:46+00:00","author":{"@id":"https:\/\/blogg.atl.nu\/abbotnas-sateri\/#\/schema\/person\/3b681683e8c9711235140b74c4aad714"},"breadcrumb":{"@id":"https:\/\/blogg.atl.nu\/abbotnas-sateri\/2025\/02\/02\/annu-mer-godseltema\/#breadcrumb"},"inLanguage":"sv-SE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blogg.atl.nu\/abbotnas-sateri\/2025\/02\/02\/annu-mer-godseltema\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/blogg.atl.nu\/abbotnas-sateri\/2025\/02\/02\/annu-mer-godseltema\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/blogg.atl.nu\/abbotnas-sateri\/"},{"@type":"ListItem","position":2,"name":"\u00c4nnu mer g\u00f6dseltema"}]},{"@type":"WebSite","@id":"https:\/\/blogg.atl.nu\/abbotnas-sateri\/#website","url":"https:\/\/blogg.atl.nu\/abbotnas-sateri\/","name":"Abbotn\u00e4s s\u00e4teri","description":"Mattias Larsson","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blogg.atl.nu\/abbotnas-sateri\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"sv-SE"},{"@type":"Person","@id":"https:\/\/blogg.atl.nu\/abbotnas-sateri\/#\/schema\/person\/3b681683e8c9711235140b74c4aad714","name":"Mattias Larsson","image":{"@type":"ImageObject","inLanguage":"sv-SE","@id":"https:\/\/blogg.atl.nu\/abbotnas-sateri\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/ab52d1a4abaa2f256164ccb2caf8dcfb?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ab52d1a4abaa2f256164ccb2caf8dcfb?s=96&d=mm&r=g","caption":"Mattias Larsson"},"sameAs":["http:\/\/abbotnas.se","facebook.com\/mattiaswlarsson"],"url":"https:\/\/blogg.atl.nu\/abbotnas-sateri\/author\/mlarsson\/"}]}},"_links":{"self":[{"href":"https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-json\/wp\/v2\/posts\/26491"}],"collection":[{"href":"https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-json\/wp\/v2\/users\/361"}],"replies":[{"embeddable":true,"href":"https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-json\/wp\/v2\/comments?post=26491"}],"version-history":[{"count":1,"href":"https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-json\/wp\/v2\/posts\/26491\/revisions"}],"predecessor-version":[{"id":26497,"href":"https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-json\/wp\/v2\/posts\/26491\/revisions\/26497"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-json\/wp\/v2\/media\/26483"}],"wp:attachment":[{"href":"https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-json\/wp\/v2\/media?parent=26491"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-json\/wp\/v2\/categories?post=26491"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-json\/wp\/v2\/tags?post=26491"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}