{"id":27675,"date":"2025-07-04T22:23:09","date_gmt":"2025-07-04T20:23:09","guid":{"rendered":"https:\/\/blogg.atl.nu\/abbotnas-sateri\/?p=27675"},"modified":"2025-07-04T22:23:09","modified_gmt":"2025-07-04T20:23:09","slug":"byte-utav-elevatorremm","status":"publish","type":"post","link":"https:\/\/blogg.atl.nu\/abbotnas-sateri\/2025\/07\/04\/byte-utav-elevatorremm\/","title":{"rendered":"Byte utav elevatorremm"},"content":{"rendered":"<p><strong>Att vara proaktiv \u00e4r n\u00e5got man f\u00e5r l\u00e4ra sig \u00e4r positivt och det kan jag st\u00f6tta fullt ut. Det \u00e4r dock inte alltid man lyckas trotts att ambitionerna finns. Idag har vi i alla fall gjort en f\u00f6rebyggande \u00e5tg\u00e4rd innan det blir f\u00f6r sent, vi har bytt remmen till den elevator som g\u00e5r mest i v\u00e5ran spannm\u00e5lsanl\u00e4ggning.\u00a0<\/strong><\/p>\n<h3>Dags att byta<\/h3>\n<p><strong>B\u00e5de under sk\u00f6rd och resten av \u00e5ret \u00e4r vi v\u00e4ldigt beroende utav v\u00e5ran &#8221;E1:a&#8221;( Elevator nummer 1 p\u00e5 styrschemat).\u00a0<\/strong>Det \u00e4r den elevator som alla spannm\u00e5l g\u00e5r i minst en g\u00e5ng, den kommer inte in i anl\u00e4ggningen om den inte passerar genom den. Det \u00e4r \u00e4ven den som g\u00e5r f\u00f6r att fylla utlastningsfickan. S\u00e5 det \u00e4r en v\u00e4ldigt viktigt och central del i anl\u00e4ggningen, man kan nog s\u00e4ga att utan den stannar allt. Det f\u00e5r allts\u00e5 inte h\u00e4nda helt enkelt. Vi \u00f6versyn av Hasse f\u00f6r ett tag sedan s\u00e5 kunde han konstatera att den b\u00f6rjade bli d\u00e5lig och nog var dags att byta om n\u00e5gon s\u00e4song. D\u00e5 tog vi beslutet att g\u00f6ra det s\u00e5 fort som m\u00f6jligt f\u00f6r s\u00e4kerhets skull. T\u00e4nk om man vet att den \u00e4r d\u00e5lig, struntar i att byta den och den g\u00e5r s\u00f6nder. D\u00e5 skulle man inte k\u00e4nna sig helt n\u00f6jd&#8230; Idag skedde detta byte.<\/p>\n<figure id=\"attachment_27652\" aria-describedby=\"caption-attachment-27652\" style=\"width: 2560px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" class=\"wp-image-27652 size-full\" src=\"https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/07\/IMG_3788-scaled.jpeg\" alt=\"\" width=\"2560\" height=\"1920\" srcset=\"https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/07\/IMG_3788-scaled.jpeg 2560w, https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/07\/IMG_3788-300x225.jpeg 300w, https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/07\/IMG_3788-1024x768.jpeg 1024w, https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/07\/IMG_3788-768x576.jpeg 768w, https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/07\/IMG_3788-1536x1152.jpeg 1536w, https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/07\/IMG_3788-2048x1536.jpeg 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/><figcaption id=\"caption-attachment-27652\" class=\"wp-caption-text\">H\u00e4r \u00e4r anledningen till bytet. P\u00e5 baksidan av remmen var den sliten och yttre gummit var p\u00e5 m\u00e5nga st\u00e4llen borta. Det var inte katastrof-l\u00e4ge, men \u00e4nd\u00e5 dags att byta. Sk\u00f6nt att kunna g\u00f6ra det i tid.<\/figcaption><\/figure>\n<h3>Hj\u00e4lp med bytet<\/h3>\n<p><strong>S\u00e5 var det sj\u00e4lva momentet med att byta remmen och jag m\u00e5ste erk\u00e4nna att jag g\u00e5tt och sett detta som ett stort och sv\u00e5rt arbetsmoment. <\/strong>Det visade sig att jag hade fel, utav anledningen att vi som vanligt n\u00e4r vi ska g\u00f6ra n\u00e5got st\u00f6rre p\u00e5 spannm\u00e5lsanl\u00e4ggningen r\u00e5dfr\u00e5gande Hasse innan och \u00e4ven kunde f\u00e5 hj\u00e4lp utav honom att g\u00f6ra bytet, med han hj\u00e4lp gick allt som en dans. Det gick b\u00e5de snabbare och var l\u00e4ttare \u00e4n jag trodde. Det \u00e4r riktigt sk\u00f6nt att ha hj\u00e4lp av n\u00e5gon som kan grejor som man inte riktigt kan sj\u00e4lv. F\u00f6r \u00e4ven om man kanske l\u00f6ser uppgiften, s\u00e5 finns det en hel del fallgropar att undvika om man tar\/f\u00e5r hj\u00e4lp. Inte bara genom tips, utan \u00e4ven genom v\u00e4gledning p\u00e5 plats. N\u00e4r v\u00e4gledningen dessutom \u00e4r den som skruvar mest \u00e4r det en riktigt bonus. Hursomhelst s\u00e5 byttes remmen snabbt och en 16 meter h\u00f6g elevator hade med hj\u00e4lp av fyra stycken f\u00e5tt ny rem straxt efter klockan 10:00 idag. Hur vi gick till v\u00e4ga syns p\u00e5 bilderna.<\/p>\n<figure id=\"attachment_27665\" aria-describedby=\"caption-attachment-27665\" style=\"width: 2560px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" class=\"wp-image-27665 size-full\" src=\"https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/07\/IMG_3764-scaled-e1751659665838.jpeg\" alt=\"\" width=\"2560\" height=\"1920\" srcset=\"https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/07\/IMG_3764-scaled-e1751659665838.jpeg 2560w, https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/07\/IMG_3764-scaled-e1751659665838-300x225.jpeg 300w, https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/07\/IMG_3764-scaled-e1751659665838-1024x768.jpeg 1024w, https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/07\/IMG_3764-scaled-e1751659665838-768x576.jpeg 768w, https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/07\/IMG_3764-scaled-e1751659665838-1536x1152.jpeg 1536w, https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/07\/IMG_3764-scaled-e1751659665838-2048x1536.jpeg 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/><figcaption id=\"caption-attachment-27665\" class=\"wp-caption-text\">En pall med delar p\u00e5 plats.<\/figcaption><\/figure>\n<figure id=\"attachment_27664\" aria-describedby=\"caption-attachment-27664\" style=\"width: 2560px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" class=\"wp-image-27664 size-full\" src=\"https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/07\/IMG_3765-scaled.jpeg\" alt=\"\" width=\"2560\" height=\"1920\" srcset=\"https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/07\/IMG_3765-scaled.jpeg 2560w, https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/07\/IMG_3765-300x225.jpeg 300w, https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/07\/IMG_3765-1024x768.jpeg 1024w, https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/07\/IMG_3765-768x576.jpeg 768w, https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/07\/IMG_3765-1536x1152.jpeg 1536w, https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/07\/IMG_3765-2048x1536.jpeg 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/><figcaption id=\"caption-attachment-27664\" class=\"wp-caption-text\">Ny remmen kom fint ihoprullad.<\/figcaption><\/figure>\n<figure id=\"attachment_27663\" aria-describedby=\"caption-attachment-27663\" style=\"width: 2560px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" class=\"wp-image-27663 size-full\" src=\"https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/07\/IMG_3768-scaled.jpeg\" alt=\"\" width=\"2560\" height=\"1920\" srcset=\"https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/07\/IMG_3768-scaled.jpeg 2560w, https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/07\/IMG_3768-300x225.jpeg 300w, https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/07\/IMG_3768-1024x768.jpeg 1024w, https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/07\/IMG_3768-768x576.jpeg 768w, https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/07\/IMG_3768-1536x1152.jpeg 1536w, https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/07\/IMG_3768-2048x1536.jpeg 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/><figcaption id=\"caption-attachment-27663\" class=\"wp-caption-text\">Hasse p\u00e5 plats f\u00f6r att skruva och leda oss andra. H\u00e4r tar han is\u00e4r gamla remmen.<\/figcaption><\/figure>\n<figure id=\"attachment_27656\" aria-describedby=\"caption-attachment-27656\" style=\"width: 2560px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" class=\"wp-image-27656 size-full\" src=\"https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/07\/IMG_3780-scaled.jpeg\" alt=\"\" width=\"2560\" height=\"1920\" srcset=\"https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/07\/IMG_3780-scaled.jpeg 2560w, https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/07\/IMG_3780-300x225.jpeg 300w, https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/07\/IMG_3780-1024x768.jpeg 1024w, https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/07\/IMG_3780-768x576.jpeg 768w, https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/07\/IMG_3780-1536x1152.jpeg 1536w, https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/07\/IMG_3780-2048x1536.jpeg 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/><figcaption id=\"caption-attachment-27656\" class=\"wp-caption-text\">Ny remmen sattes upp f\u00f6r att vara l\u00e4tt att rulla fram.<\/figcaption><\/figure>\n<figure id=\"attachment_27661\" aria-describedby=\"caption-attachment-27661\" style=\"width: 2560px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" class=\"wp-image-27661 size-full\" src=\"https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/07\/IMG_3772-scaled.jpeg\" alt=\"\" width=\"2560\" height=\"1920\" srcset=\"https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/07\/IMG_3772-scaled.jpeg 2560w, https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/07\/IMG_3772-300x225.jpeg 300w, https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/07\/IMG_3772-1024x768.jpeg 1024w, https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/07\/IMG_3772-768x576.jpeg 768w, https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/07\/IMG_3772-1536x1152.jpeg 1536w, https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/07\/IMG_3772-2048x1536.jpeg 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/><figcaption id=\"caption-attachment-27661\" class=\"wp-caption-text\">Ny remmen f\u00e4sts i gamla remmen. Den gamla remmen anv\u00e4ndes f\u00f6r att dra runt den nya remmen.<\/figcaption><\/figure>\n<figure id=\"attachment_27660\" aria-describedby=\"caption-attachment-27660\" style=\"width: 2560px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" class=\"wp-image-27660 size-full\" src=\"https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/07\/IMG_3773-scaled.jpeg\" alt=\"\" width=\"2560\" height=\"1920\" srcset=\"https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/07\/IMG_3773-scaled.jpeg 2560w, https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/07\/IMG_3773-300x225.jpeg 300w, https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/07\/IMG_3773-1024x768.jpeg 1024w, https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/07\/IMG_3773-768x576.jpeg 768w, https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/07\/IMG_3773-1536x1152.jpeg 1536w, https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/07\/IMG_3773-2048x1536.jpeg 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/><figcaption id=\"caption-attachment-27660\" class=\"wp-caption-text\">De gamla skoporna som det inte var n\u00e5got fel p\u00e5 anv\u00e4ndes igen och defekta, slitna skopor lades \u00e5t sidan. Skoporna lossades helt enkelt fr\u00e5n den gamla remmen och sattes p\u00e5 den nya vartefter allt snurrades runt.<\/figcaption><\/figure>\n<figure id=\"attachment_27659\" aria-describedby=\"caption-attachment-27659\" style=\"width: 2560px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" class=\"wp-image-27659 size-full\" src=\"https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/07\/IMG_3776-scaled.jpeg\" alt=\"\" width=\"2560\" height=\"1920\" srcset=\"https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/07\/IMG_3776-scaled.jpeg 2560w, https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/07\/IMG_3776-300x225.jpeg 300w, https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/07\/IMG_3776-1024x768.jpeg 1024w, https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/07\/IMG_3776-768x576.jpeg 768w, https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/07\/IMG_3776-1536x1152.jpeg 1536w, https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/07\/IMG_3776-2048x1536.jpeg 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/><figcaption id=\"caption-attachment-27659\" class=\"wp-caption-text\">Gamla skopor men nya skruvar, muttrar och brickor. Allt sorterat snyggt f\u00f6r effektiv montering.<\/figcaption><\/figure>\n<figure id=\"attachment_27657\" aria-describedby=\"caption-attachment-27657\" style=\"width: 2560px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" class=\"wp-image-27657 size-full\" src=\"https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/07\/IMG_3779-scaled.jpeg\" alt=\"\" width=\"2560\" height=\"1920\" srcset=\"https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/07\/IMG_3779-scaled.jpeg 2560w, https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/07\/IMG_3779-300x225.jpeg 300w, https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/07\/IMG_3779-1024x768.jpeg 1024w, https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/07\/IMG_3779-768x576.jpeg 768w, https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/07\/IMG_3779-1536x1152.jpeg 1536w, https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/07\/IMG_3779-2048x1536.jpeg 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/><figcaption id=\"caption-attachment-27657\" class=\"wp-caption-text\">Loke f\u00e4ster skopor<\/figcaption><\/figure>\n<figure id=\"attachment_27654\" aria-describedby=\"caption-attachment-27654\" style=\"width: 2560px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" class=\"wp-image-27654 size-full\" src=\"https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/07\/IMG_3784-scaled.jpeg\" alt=\"\" width=\"2560\" height=\"1920\" srcset=\"https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/07\/IMG_3784-scaled.jpeg 2560w, https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/07\/IMG_3784-300x225.jpeg 300w, https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/07\/IMG_3784-1024x768.jpeg 1024w, https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/07\/IMG_3784-768x576.jpeg 768w, https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/07\/IMG_3784-1536x1152.jpeg 1536w, https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/07\/IMG_3784-2048x1536.jpeg 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/><figcaption id=\"caption-attachment-27654\" class=\"wp-caption-text\">Janne, Loke och Hasse sk\u00f6tte skruvandet.<\/figcaption><\/figure>\n<figure id=\"attachment_27653\" aria-describedby=\"caption-attachment-27653\" style=\"width: 2560px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" class=\"wp-image-27653 size-full\" src=\"https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/07\/IMG_3786-scaled.jpeg\" alt=\"\" width=\"2560\" height=\"1920\" srcset=\"https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/07\/IMG_3786-scaled.jpeg 2560w, https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/07\/IMG_3786-300x225.jpeg 300w, https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/07\/IMG_3786-1024x768.jpeg 1024w, https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/07\/IMG_3786-768x576.jpeg 768w, https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/07\/IMG_3786-1536x1152.jpeg 1536w, https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/07\/IMG_3786-2048x1536.jpeg 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/><figcaption id=\"caption-attachment-27653\" class=\"wp-caption-text\">Min roll var att h\u00e5lla i och rulla runt remmen.<\/figcaption><\/figure>\n<figure id=\"attachment_27651\" aria-describedby=\"caption-attachment-27651\" style=\"width: 2560px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" class=\"wp-image-27651 size-full\" src=\"https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/07\/IMG_3792-scaled.jpeg\" alt=\"\" width=\"2560\" height=\"1920\" srcset=\"https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/07\/IMG_3792-scaled.jpeg 2560w, https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/07\/IMG_3792-300x225.jpeg 300w, https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/07\/IMG_3792-1024x768.jpeg 1024w, https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/07\/IMG_3792-768x576.jpeg 768w, https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/07\/IMG_3792-1536x1152.jpeg 1536w, https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/07\/IMG_3792-2048x1536.jpeg 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/><figcaption id=\"caption-attachment-27651\" class=\"wp-caption-text\">Till slut kunde nya remmen s\u00e4ttas ihop och sp\u00e4nnas. Allt blev klart och provk\u00f6rt. Tyv\u00e4rr blev dock provk\u00f6rningen framskjuten p\u00e5 grund utav en l\u00e5ngvarigt oplanerat str\u00f6mavbrott.<\/figcaption><\/figure>\n<h3>Lite annat som h\u00e4nder i bildrapport<\/h3>\n<figure id=\"attachment_27672\" aria-describedby=\"caption-attachment-27672\" style=\"width: 2560px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" class=\"wp-image-27672 size-full\" src=\"https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/07\/IMG_3699-scaled.jpeg\" alt=\"\" width=\"2560\" height=\"1920\" srcset=\"https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/07\/IMG_3699-scaled.jpeg 2560w, https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/07\/IMG_3699-300x225.jpeg 300w, https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/07\/IMG_3699-1024x768.jpeg 1024w, https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/07\/IMG_3699-768x576.jpeg 768w, https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/07\/IMG_3699-1536x1152.jpeg 1536w, https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/07\/IMG_3699-2048x1536.jpeg 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/><figcaption id=\"caption-attachment-27672\" class=\"wp-caption-text\">Valtran har f\u00e5t p\u00e5 sig sina breda, h\u00e5rda och tunga hjul nu.<\/figcaption><\/figure>\n<figure id=\"attachment_27673\" aria-describedby=\"caption-attachment-27673\" style=\"width: 2560px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" class=\"wp-image-27673 size-full\" src=\"https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/07\/IMG_3703-scaled.jpeg\" alt=\"\" width=\"2560\" height=\"1920\" srcset=\"https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/07\/IMG_3703-scaled.jpeg 2560w, https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/07\/IMG_3703-300x225.jpeg 300w, https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/07\/IMG_3703-1024x768.jpeg 1024w, https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/07\/IMG_3703-768x576.jpeg 768w, https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/07\/IMG_3703-1536x1152.jpeg 1536w, https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/07\/IMG_3703-2048x1536.jpeg 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/><figcaption id=\"caption-attachment-27673\" class=\"wp-caption-text\">Redo f\u00f6r h\u00f6stuppdrag.<\/figcaption><\/figure>\n<figure id=\"attachment_27670\" aria-describedby=\"caption-attachment-27670\" style=\"width: 2560px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" class=\"wp-image-27670 size-full\" src=\"https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/07\/IMG_3718-scaled.jpeg\" alt=\"\" width=\"2560\" height=\"1920\" srcset=\"https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/07\/IMG_3718-scaled.jpeg 2560w, https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/07\/IMG_3718-300x225.jpeg 300w, https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/07\/IMG_3718-1024x768.jpeg 1024w, https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/07\/IMG_3718-768x576.jpeg 768w, https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/07\/IMG_3718-1536x1152.jpeg 1536w, https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/07\/IMG_3718-2048x1536.jpeg 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/><figcaption id=\"caption-attachment-27670\" class=\"wp-caption-text\">Vi gjorde om lite i hytten inf\u00f6r den h\u00e4r s\u00e4songen. Valtran egna armst\u00f6d hamnade i bakrutan och armst\u00f6det till Norematen hamnade ist\u00e4llet d\u00e4r Valtran armst\u00f6d brukar sitta. Det blev riktigt bra och mer ergonomiskt att k\u00f6ra.<\/figcaption><\/figure>\n<figure id=\"attachment_27671\" aria-describedby=\"caption-attachment-27671\" style=\"width: 2560px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" class=\"wp-image-27671 size-full\" src=\"https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/07\/IMG_3720-scaled.jpeg\" alt=\"\" width=\"2560\" height=\"1920\" srcset=\"https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/07\/IMG_3720-scaled.jpeg 2560w, https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/07\/IMG_3720-300x225.jpeg 300w, https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/07\/IMG_3720-1024x768.jpeg 1024w, https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/07\/IMG_3720-768x576.jpeg 768w, https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/07\/IMG_3720-1536x1152.jpeg 1536w, https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/07\/IMG_3720-2048x1536.jpeg 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/><figcaption id=\"caption-attachment-27671\" class=\"wp-caption-text\">Kamera f\u00f6r att undvika en del nacksp\u00e4rr. Fungerar bra vid l\u00e4ttare k\u00f6rning.<\/figcaption><\/figure>\n<figure id=\"attachment_27666\" aria-describedby=\"caption-attachment-27666\" style=\"width: 2560px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" class=\"wp-image-27666 size-full\" src=\"https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/07\/IMG_3742-scaled.jpeg\" alt=\"\" width=\"2560\" height=\"1920\" srcset=\"https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/07\/IMG_3742-scaled.jpeg 2560w, https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/07\/IMG_3742-300x225.jpeg 300w, https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/07\/IMG_3742-1024x768.jpeg 1024w, https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/07\/IMG_3742-768x576.jpeg 768w, https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/07\/IMG_3742-1536x1152.jpeg 1536w, https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/07\/IMG_3742-2048x1536.jpeg 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/><figcaption id=\"caption-attachment-27666\" class=\"wp-caption-text\">St\u00e4dning runt vallbrotet efter undank\u00f6rning av ris. Sm\u00e5 grenar fr\u00e4ses s\u00f6nder med betesputsen.<\/figcaption><\/figure>\n<figure id=\"attachment_27667\" aria-describedby=\"caption-attachment-27667\" style=\"width: 2560px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" class=\"wp-image-27667 size-full\" src=\"https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/07\/IMG_3756-scaled.jpeg\" alt=\"\" width=\"2560\" height=\"1920\" srcset=\"https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/07\/IMG_3756-scaled.jpeg 2560w, https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/07\/IMG_3756-300x225.jpeg 300w, https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/07\/IMG_3756-1024x768.jpeg 1024w, https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/07\/IMG_3756-768x576.jpeg 768w, https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/07\/IMG_3756-1536x1152.jpeg 1536w, https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/07\/IMG_3756-2048x1536.jpeg 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/><figcaption id=\"caption-attachment-27667\" class=\"wp-caption-text\">Loke och Norematen jobbar sig runt de diken som ska rensas p\u00e5 vallbrotten. Detta f\u00f6r att underl\u00e4tta rensningen med gr\u00e4vmaskinen.<\/figcaption><\/figure>\n<figure id=\"attachment_27668\" aria-describedby=\"caption-attachment-27668\" style=\"width: 2560px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" class=\"wp-image-27668 size-full\" src=\"https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/07\/IMG_3757-scaled.jpeg\" alt=\"\" width=\"2560\" height=\"1920\" srcset=\"https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/07\/IMG_3757-scaled.jpeg 2560w, https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/07\/IMG_3757-300x225.jpeg 300w, https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/07\/IMG_3757-1024x768.jpeg 1024w, https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/07\/IMG_3757-768x576.jpeg 768w, https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/07\/IMG_3757-1536x1152.jpeg 1536w, https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/07\/IMG_3757-2048x1536.jpeg 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/><figcaption id=\"caption-attachment-27668\" class=\"wp-caption-text\">Gr\u00e4vmaskinen \u00e4r nu ny besiktad och redo f\u00f6r ytterligare ett \u00e5r i tj\u00e4nst.<\/figcaption><\/figure>\n<p>Trevlig helg! Vi ska fira v\u00e5ran med att vaccinera den andra dosen bl\u00e5tunge-vaccin till v\u00e5ra djur p\u00e5 bete.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Att vara proaktiv \u00e4r n\u00e5got man f\u00e5r l\u00e4ra sig \u00e4r positivt och det kan jag st\u00f6tta fullt ut. Det \u00e4r dock inte alltid man lyckas trotts att ambitionerna finns. Idag har vi i alla fall gjort en f\u00f6rebyggande \u00e5tg\u00e4rd innan det blir f\u00f6r sent, vi har bytt remmen till den elevator som g\u00e5r mest i&#8230;<\/p>\n","protected":false},"author":361,"featured_media":27661,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Byte utav elevatorremm - Abbotn\u00e4s s\u00e4teri<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blogg.atl.nu\/abbotnas-sateri\/2025\/07\/04\/byte-utav-elevatorremm\/\" \/>\n<meta property=\"og:locale\" content=\"sv_SE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Byte utav elevatorremm - Abbotn\u00e4s s\u00e4teri\" \/>\n<meta property=\"og:description\" content=\"Att vara proaktiv \u00e4r n\u00e5got man f\u00e5r l\u00e4ra sig \u00e4r positivt och det kan jag st\u00f6tta fullt ut. Det \u00e4r dock inte alltid man lyckas trotts att ambitionerna finns. Idag har vi i alla fall gjort en f\u00f6rebyggande \u00e5tg\u00e4rd innan det blir f\u00f6r sent, vi har bytt remmen till den elevator som g\u00e5r mest i...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blogg.atl.nu\/abbotnas-sateri\/2025\/07\/04\/byte-utav-elevatorremm\/\" \/>\n<meta property=\"og:site_name\" content=\"Abbotn\u00e4s s\u00e4teri\" \/>\n<meta property=\"article:author\" content=\"facebook.com\/mattiaswlarsson\" \/>\n<meta property=\"article:published_time\" content=\"2025-07-04T20:23:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/07\/IMG_3772-scaled.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1920\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Mattias Larsson\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Skriven av\" \/>\n\t<meta name=\"twitter:data1\" content=\"Mattias Larsson\" \/>\n\t<meta name=\"twitter:label2\" content=\"Ber\u00e4knad l\u00e4stid\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minuter\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/blogg.atl.nu\/abbotnas-sateri\/2025\/07\/04\/byte-utav-elevatorremm\/\",\"url\":\"https:\/\/blogg.atl.nu\/abbotnas-sateri\/2025\/07\/04\/byte-utav-elevatorremm\/\",\"name\":\"Byte utav elevatorremm - Abbotn\u00e4s s\u00e4teri\",\"isPartOf\":{\"@id\":\"https:\/\/blogg.atl.nu\/abbotnas-sateri\/#website\"},\"datePublished\":\"2025-07-04T20:23:09+00:00\",\"dateModified\":\"2025-07-04T20:23:09+00:00\",\"author\":{\"@id\":\"https:\/\/blogg.atl.nu\/abbotnas-sateri\/#\/schema\/person\/3b681683e8c9711235140b74c4aad714\"},\"breadcrumb\":{\"@id\":\"https:\/\/blogg.atl.nu\/abbotnas-sateri\/2025\/07\/04\/byte-utav-elevatorremm\/#breadcrumb\"},\"inLanguage\":\"sv-SE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/blogg.atl.nu\/abbotnas-sateri\/2025\/07\/04\/byte-utav-elevatorremm\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/blogg.atl.nu\/abbotnas-sateri\/2025\/07\/04\/byte-utav-elevatorremm\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/blogg.atl.nu\/abbotnas-sateri\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Byte utav elevatorremm\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/blogg.atl.nu\/abbotnas-sateri\/#website\",\"url\":\"https:\/\/blogg.atl.nu\/abbotnas-sateri\/\",\"name\":\"Abbotn\u00e4s s\u00e4teri\",\"description\":\"Mattias Larsson\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/blogg.atl.nu\/abbotnas-sateri\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"sv-SE\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/blogg.atl.nu\/abbotnas-sateri\/#\/schema\/person\/3b681683e8c9711235140b74c4aad714\",\"name\":\"Mattias Larsson\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"sv-SE\",\"@id\":\"https:\/\/blogg.atl.nu\/abbotnas-sateri\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/ab52d1a4abaa2f256164ccb2caf8dcfb?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/ab52d1a4abaa2f256164ccb2caf8dcfb?s=96&d=mm&r=g\",\"caption\":\"Mattias Larsson\"},\"sameAs\":[\"http:\/\/abbotnas.se\",\"facebook.com\/mattiaswlarsson\"],\"url\":\"https:\/\/blogg.atl.nu\/abbotnas-sateri\/author\/mlarsson\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Byte utav elevatorremm - Abbotn\u00e4s s\u00e4teri","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blogg.atl.nu\/abbotnas-sateri\/2025\/07\/04\/byte-utav-elevatorremm\/","og_locale":"sv_SE","og_type":"article","og_title":"Byte utav elevatorremm - Abbotn\u00e4s s\u00e4teri","og_description":"Att vara proaktiv \u00e4r n\u00e5got man f\u00e5r l\u00e4ra sig \u00e4r positivt och det kan jag st\u00f6tta fullt ut. Det \u00e4r dock inte alltid man lyckas trotts att ambitionerna finns. Idag har vi i alla fall gjort en f\u00f6rebyggande \u00e5tg\u00e4rd innan det blir f\u00f6r sent, vi har bytt remmen till den elevator som g\u00e5r mest i...","og_url":"https:\/\/blogg.atl.nu\/abbotnas-sateri\/2025\/07\/04\/byte-utav-elevatorremm\/","og_site_name":"Abbotn\u00e4s s\u00e4teri","article_author":"facebook.com\/mattiaswlarsson","article_published_time":"2025-07-04T20:23:09+00:00","og_image":[{"width":2560,"height":1920,"url":"https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-content\/uploads\/sites\/41\/2025\/07\/IMG_3772-scaled.jpeg","type":"image\/jpeg"}],"author":"Mattias Larsson","twitter_card":"summary_large_image","twitter_misc":{"Skriven av":"Mattias Larsson","Ber\u00e4knad l\u00e4stid":"8 minuter"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/blogg.atl.nu\/abbotnas-sateri\/2025\/07\/04\/byte-utav-elevatorremm\/","url":"https:\/\/blogg.atl.nu\/abbotnas-sateri\/2025\/07\/04\/byte-utav-elevatorremm\/","name":"Byte utav elevatorremm - Abbotn\u00e4s s\u00e4teri","isPartOf":{"@id":"https:\/\/blogg.atl.nu\/abbotnas-sateri\/#website"},"datePublished":"2025-07-04T20:23:09+00:00","dateModified":"2025-07-04T20:23:09+00:00","author":{"@id":"https:\/\/blogg.atl.nu\/abbotnas-sateri\/#\/schema\/person\/3b681683e8c9711235140b74c4aad714"},"breadcrumb":{"@id":"https:\/\/blogg.atl.nu\/abbotnas-sateri\/2025\/07\/04\/byte-utav-elevatorremm\/#breadcrumb"},"inLanguage":"sv-SE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blogg.atl.nu\/abbotnas-sateri\/2025\/07\/04\/byte-utav-elevatorremm\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/blogg.atl.nu\/abbotnas-sateri\/2025\/07\/04\/byte-utav-elevatorremm\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/blogg.atl.nu\/abbotnas-sateri\/"},{"@type":"ListItem","position":2,"name":"Byte utav elevatorremm"}]},{"@type":"WebSite","@id":"https:\/\/blogg.atl.nu\/abbotnas-sateri\/#website","url":"https:\/\/blogg.atl.nu\/abbotnas-sateri\/","name":"Abbotn\u00e4s s\u00e4teri","description":"Mattias Larsson","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blogg.atl.nu\/abbotnas-sateri\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"sv-SE"},{"@type":"Person","@id":"https:\/\/blogg.atl.nu\/abbotnas-sateri\/#\/schema\/person\/3b681683e8c9711235140b74c4aad714","name":"Mattias Larsson","image":{"@type":"ImageObject","inLanguage":"sv-SE","@id":"https:\/\/blogg.atl.nu\/abbotnas-sateri\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/ab52d1a4abaa2f256164ccb2caf8dcfb?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ab52d1a4abaa2f256164ccb2caf8dcfb?s=96&d=mm&r=g","caption":"Mattias Larsson"},"sameAs":["http:\/\/abbotnas.se","facebook.com\/mattiaswlarsson"],"url":"https:\/\/blogg.atl.nu\/abbotnas-sateri\/author\/mlarsson\/"}]}},"_links":{"self":[{"href":"https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-json\/wp\/v2\/posts\/27675"}],"collection":[{"href":"https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-json\/wp\/v2\/users\/361"}],"replies":[{"embeddable":true,"href":"https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-json\/wp\/v2\/comments?post=27675"}],"version-history":[{"count":2,"href":"https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-json\/wp\/v2\/posts\/27675\/revisions"}],"predecessor-version":[{"id":27677,"href":"https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-json\/wp\/v2\/posts\/27675\/revisions\/27677"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-json\/wp\/v2\/media\/27661"}],"wp:attachment":[{"href":"https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-json\/wp\/v2\/media?parent=27675"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-json\/wp\/v2\/categories?post=27675"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogg.atl.nu\/abbotnas-sateri\/wp-json\/wp\/v2\/tags?post=27675"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}